{"id":10649,"date":"2021-05-11T09:14:22","date_gmt":"2021-05-11T09:14:22","guid":{"rendered":"https:\/\/www.bulaoutdoor.nl\/?post_type=product&#038;p=10649"},"modified":"2025-05-30T07:08:38","modified_gmt":"2025-05-30T07:08:38","slug":"plaque-de-distribution-pour-loval-xl-400","status":"publish","type":"product","link":"https:\/\/bulaoutdoor.nl\/fr\/product\/verdeelplaat-voor-de-oval-xl-400\/","title":{"rendered":"Plaque de distribution pour l'Oval XL 400"},"content":{"rendered":"<p>Cette plaque en fonte offre une zone indirecte et une zone directe.<\/p>\n<ul>\n<li>La plaque est en fonte.<\/li>\n<li>Pr\u00e9voyez diff\u00e9rentes zones de cuisson dans le barbecue pour diff\u00e9rentes pr\u00e9parations.<\/li>\n<li>Sauver du charbon de bois.<\/li>\n<li>Fabriqu\u00e9 sur mesure pour le Primo XL 400.<\/li>\n<\/ul>\n<p>Commandez la plaque de distribution pour l'Oval XL 400 directement aupr\u00e8s de <a href=\"https:\/\/bulaoutdoor.nl\/fr\/categorie-de-produits\/bbq\/\">Bula Outdoor, votre sp\u00e9cialiste du barbecue !<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10651\" src=\"https:\/\/www.bulaoutdoor.nl\/wp-content\/uploads\/2021\/04\/verdeelplaatgif.gif\" alt=\"\" width=\"256\" height=\"286\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Cette plaque permet de cr\u00e9er une zone indirecte et une zone directe et d'\u00e9conomiser du charbon de bois.<\/p>","protected":false},"featured_media":10972,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[392],"product_tag":[506,413,414],"class_list":["post-10649","product","type-product","status-publish","has-post-thumbnail","product_cat-oval-400-xl-primo-accessoires","product_tag-pg00334","product_tag-verdeelplaat-primo","product_tag-verdeelplaat-primo-xl-400","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verdeelplaat voor de Oval XL 400 &#8211; Bula Outdoor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bulaoutdoor.nl\/fr\/produit\/plaque-de-distribution-pour-loval-xl-400\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verdeelplaat voor de Oval XL 400 &#8211; Bula Outdoor\" \/>\n<meta property=\"og:description\" content=\"Deze plaat zorgt voor een indirecte en een directe zone en bespaard houtskool.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bulaoutdoor.nl\/fr\/produit\/plaque-de-distribution-pour-loval-xl-400\/\" \/>\n<meta property=\"og:site_name\" content=\"Bula Outdoor\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-30T07:08:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bulaoutdoor.nl\/wp-content\/uploads\/2021\/05\/verdeelplaat-vuurbox-2_SCALED.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/product\\\/verdeelplaat-voor-de-oval-xl-400\\\/\",\"url\":\"https:\\\/\\\/bulaoutdoor.nl\\\/product\\\/verdeelplaat-voor-de-oval-xl-400\\\/\",\"name\":\"Verdeelplaat voor de Oval XL 400 &#8211; Bula Outdoor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/product\\\/verdeelplaat-voor-de-oval-xl-400\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/product\\\/verdeelplaat-voor-de-oval-xl-400\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bulaoutdoor.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/verdeelplaat-vuurbox-2_SCALED.jpg\",\"datePublished\":\"2021-05-11T09:14:22+00:00\",\"dateModified\":\"2025-05-30T07:08:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/product\\\/verdeelplaat-voor-de-oval-xl-400\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bulaoutdoor.nl\\\/product\\\/verdeelplaat-voor-de-oval-xl-400\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/product\\\/verdeelplaat-voor-de-oval-xl-400\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bulaoutdoor.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/verdeelplaat-vuurbox-2_SCALED.jpg\",\"contentUrl\":\"https:\\\/\\\/bulaoutdoor.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/verdeelplaat-vuurbox-2_SCALED.jpg\",\"width\":480,\"height\":480,\"caption\":\"verdeelplaat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/product\\\/verdeelplaat-voor-de-oval-xl-400\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bulaoutdoor.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online BBQ kopen\",\"item\":\"https:\\\/\\\/bulaoutdoor.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verdeelplaat voor de Oval XL 400\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/#website\",\"url\":\"https:\\\/\\\/bulaoutdoor.nl\\\/\",\"name\":\"Bula Outdoor\",\"description\":\"Voor uw buitenhaard, BBQ, tuinfakkel en houtoven\",\"publisher\":{\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bulaoutdoor.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/#organization\",\"name\":\"Bula Outdoor\",\"url\":\"https:\\\/\\\/bulaoutdoor.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bulaoutdoor.nl\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bulaoutdoor-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.bulaoutdoor.nl\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bulaoutdoor-logo.png\",\"width\":324,\"height\":91,\"caption\":\"Bula Outdoor\"},\"image\":{\"@id\":\"https:\\\/\\\/bulaoutdoor.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plaque de distribution pour l'Oval XL 400 - Bula Outdoor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bulaoutdoor.nl\/fr\/produit\/plaque-de-distribution-pour-loval-xl-400\/","og_locale":"fr_FR","og_type":"article","og_title":"Verdeelplaat voor de Oval XL 400 &#8211; Bula Outdoor","og_description":"Deze plaat zorgt voor een indirecte en een directe zone en bespaard houtskool.","og_url":"https:\/\/bulaoutdoor.nl\/fr\/produit\/plaque-de-distribution-pour-loval-xl-400\/","og_site_name":"Bula Outdoor","article_modified_time":"2025-05-30T07:08:38+00:00","og_image":[{"width":480,"height":480,"url":"https:\/\/bulaoutdoor.nl\/wp-content\/uploads\/2021\/05\/verdeelplaat-vuurbox-2_SCALED.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bulaoutdoor.nl\/product\/verdeelplaat-voor-de-oval-xl-400\/","url":"https:\/\/bulaoutdoor.nl\/product\/verdeelplaat-voor-de-oval-xl-400\/","name":"Plaque de distribution pour l'Oval XL 400 - Bula Outdoor","isPartOf":{"@id":"https:\/\/bulaoutdoor.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bulaoutdoor.nl\/product\/verdeelplaat-voor-de-oval-xl-400\/#primaryimage"},"image":{"@id":"https:\/\/bulaoutdoor.nl\/product\/verdeelplaat-voor-de-oval-xl-400\/#primaryimage"},"thumbnailUrl":"https:\/\/bulaoutdoor.nl\/wp-content\/uploads\/2021\/05\/verdeelplaat-vuurbox-2_SCALED.jpg","datePublished":"2021-05-11T09:14:22+00:00","dateModified":"2025-05-30T07:08:38+00:00","breadcrumb":{"@id":"https:\/\/bulaoutdoor.nl\/product\/verdeelplaat-voor-de-oval-xl-400\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bulaoutdoor.nl\/product\/verdeelplaat-voor-de-oval-xl-400\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bulaoutdoor.nl\/product\/verdeelplaat-voor-de-oval-xl-400\/#primaryimage","url":"https:\/\/bulaoutdoor.nl\/wp-content\/uploads\/2021\/05\/verdeelplaat-vuurbox-2_SCALED.jpg","contentUrl":"https:\/\/bulaoutdoor.nl\/wp-content\/uploads\/2021\/05\/verdeelplaat-vuurbox-2_SCALED.jpg","width":480,"height":480,"caption":"verdeelplaat"},{"@type":"BreadcrumbList","@id":"https:\/\/bulaoutdoor.nl\/product\/verdeelplaat-voor-de-oval-xl-400\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bulaoutdoor.nl\/"},{"@type":"ListItem","position":2,"name":"Online BBQ kopen","item":"https:\/\/bulaoutdoor.nl\/"},{"@type":"ListItem","position":3,"name":"Verdeelplaat voor de Oval XL 400"}]},{"@type":"WebSite","@id":"https:\/\/bulaoutdoor.nl\/#website","url":"https:\/\/bulaoutdoor.nl\/","name":"Bula Outdoor","description":"Pour votre chemin\u00e9e ext\u00e9rieure, votre barbecue, votre torche de jardin et votre four \u00e0 bois","publisher":{"@id":"https:\/\/bulaoutdoor.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bulaoutdoor.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bulaoutdoor.nl\/#organization","name":"Bula Outdoor","url":"https:\/\/bulaoutdoor.nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bulaoutdoor.nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.bulaoutdoor.nl\/wp-content\/uploads\/2018\/04\/bulaoutdoor-logo.png","contentUrl":"https:\/\/www.bulaoutdoor.nl\/wp-content\/uploads\/2018\/04\/bulaoutdoor-logo.png","width":324,"height":91,"caption":"Bula Outdoor"},"image":{"@id":"https:\/\/bulaoutdoor.nl\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bulaoutdoor.nl\/fr\/wp-json\/wp\/v2\/product\/10649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bulaoutdoor.nl\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bulaoutdoor.nl\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bulaoutdoor.nl\/fr\/wp-json\/wp\/v2\/comments?post=10649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bulaoutdoor.nl\/fr\/wp-json\/wp\/v2\/media\/10972"}],"wp:attachment":[{"href":"https:\/\/bulaoutdoor.nl\/fr\/wp-json\/wp\/v2\/media?parent=10649"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bulaoutdoor.nl\/fr\/wp-json\/wp\/v2\/product_brand?post=10649"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bulaoutdoor.nl\/fr\/wp-json\/wp\/v2\/product_cat?post=10649"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bulaoutdoor.nl\/fr\/wp-json\/wp\/v2\/product_tag?post=10649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}